{"id":10594,"date":"2023-02-28T11:01:14","date_gmt":"2023-02-28T14:01:14","guid":{"rendered":"http:\/\/www.todovinos.cl\/wp2\/?p=10594"},"modified":"2023-02-28T11:01:14","modified_gmt":"2023-02-28T14:01:14","slug":"sector-del-vino-sufre-consecuencias-climaticas-antes-que-cualquier-otro","status":"publish","type":"post","link":"https:\/\/www.todovinos.cl\/wp2\/2023\/02\/28\/sector-del-vino-sufre-consecuencias-climaticas-antes-que-cualquier-otro\/","title":{"rendered":"Sector del vino sufre consecuencias clim\u00e1ticas antes que cualquier otro"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.todovinos.cl\/wp2\/wp-content\/uploads\/2023\/02\/matorres2.jpg\" alt=\"\" class=\"wp-image-10595\" width=\"327\" height=\"245\" srcset=\"https:\/\/www.todovinos.cl\/wp2\/wp-content\/uploads\/2023\/02\/matorres2.jpg 557w, https:\/\/www.todovinos.cl\/wp2\/wp-content\/uploads\/2023\/02\/matorres2-150x113.jpg 150w, https:\/\/www.todovinos.cl\/wp2\/wp-content\/uploads\/2023\/02\/matorres2-300x225.jpg 300w\" sizes=\"auto, (max-width: 327px) 100vw, 327px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Como presidente y cofundador de las International Wineries for Climate Action (IWCA), y tras crear el programa Torres &amp; Earth para contribuir a mitigar el calentamiento global y promover la adaptaci\u00f3n al nuevo escenario clim\u00e1tico, Miguel A. Torres, centra ahora su labor en concienciar al sector vitivin\u00edcola y a la sociedad en su conjunto de la necesidad de actuar frente a la crisis clim\u00e1tica, asuntos a que se refiere en entrevista al medio elconfidencial.com<br><br> &#8212;<em>Como est\u00e1 observando la evoluci\u00f3n del cambio clim\u00e1tico desde el cultivo del vi\u00f1edo, \u00bfes cierto que los impactos se est\u00e1n acelerando?<\/em> <br><br> &#8211;Lo vemos cada a\u00f1o, pero en 2022 se han batido todos los r\u00e9cords y la viticultura se va haciendo cada vez m\u00e1s dif\u00edcil. Las tormentas son m\u00e1s fuertes, las sequ\u00edas m\u00e1s extremas, las heladas primaverales y las olas de calor m\u00e1s frecuentes, tambi\u00e9n hay m\u00e1s incendios\u2026 Siempre digo que la vi\u00f1a se parece en cierto modo a los canarios que antiguamente llevaban consigo los mineros al bajar a la mina cuando hab\u00eda peligro de gris\u00fa: si el canario se asfixiaba hab\u00eda que salir r\u00e1pidamente al exterior. El sector del vino est\u00e1 sufriendo las consecuencias clim\u00e1ticas mucho antes que cualquier otro sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;<em>Sin embargo, y pese a esa constataci\u00f3n, siguen siendo pocas las bodegas que est\u00e1n emprendiendo labores de adaptaci\u00f3n y mitigaci\u00f3n<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;Queda camino por recorrer, pero por suerte las cosas est\u00e1n cambiando y cada vez somos m\u00e1s las bodegas que nos esforzamos en reducir nuestra huella de carbono. El tema es que debemos actuar ya, no podemos esperar, y debemos hacerlo de una manera decidida y con inversi\u00f3n. En nuestro caso, desde que pusimos en marcha la estrategia ambiental Torres &amp; Earth, en 2008, hemos invertido 18 millones de euros en medidas de mitigaci\u00f3n y adaptaci\u00f3n, como la compra de terrenos en altura y proyectos de reforestaci\u00f3n. Ya hemos reducido m\u00e1s del 35% las emisiones de CO\u2082 por botella en todo el alcance, desde la vi\u00f1a al consumidor. Nuestro objetivo es llegar al 60% en 2030 y convertirnos en una bodega de emisiones cero netas antes de 2040.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;<em>En 2019, fund\u00f3 junto a otras bodegas del mundo la International Wineries for Climate Action (IWCA) para promover la reducci\u00f3n de las emisiones de carbono en el sector vin\u00edcola. \u00bfQu\u00e9 acogida est\u00e1 teniendo esta iniciativa?<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;Muy buena. Arranc\u00f3 poco a poco, pero ahora ya somos unas 80 bodegas de 10 pa\u00edses diferentes. Lo importante aqu\u00ed es que tenemos un enfoque cient\u00edfico y unos objetivos ambiciosos de reducci\u00f3n de emisiones que deben ser auditados cada a\u00f1o, o cada dos a\u00f1os en el caso de las bodegas peque\u00f1as. Y tenemos una certificaci\u00f3n que lo avala. Somos un grupo de trabajo colaborativo en el que se comparten experiencias y conocimientos para avanzar juntos y de manera m\u00e1s efectiva hacia la descarbonizaci\u00f3n del sector a nivel global. Tambi\u00e9n hemos sido la primera organizaci\u00f3n agr\u00edcola en ser admitidos a la iniciativa Race to Zero de las Naciones Unidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;<em>Muchos bodegueros pueden pensar que su actividad no est\u00e1 entre las principales causas del aumento de las emisiones y que, por lo tanto, son otros los que deben liderar la respuesta al cambio clim\u00e1<\/em>tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;Estamos inmersos en una crisis clim\u00e1tica sin precedentes. Hay que actuar en todos los sectores y a todos los niveles. El sector del vino es uno de los grandes afectados, ya que, como dec\u00eda antes, el cultivo de la vi\u00f1a se est\u00e1 haciendo cada vez m\u00e1s dif\u00edcil y esto puede llegar a afectar la calidad de los vinos. Precisamente creo que el sector del vino tiene la oportunidad de abanderar esta lucha clim\u00e1tica con iniciativas conjuntas como las IWCA y ser un ejemplo para otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;<em>Adem\u00e1s de la incorporaci\u00f3n del riego, el cambio de variedades y otras t\u00e9cnicas de cultivo, muchos est\u00e1n desplazando sus vi\u00f1edos en altura, \u00bfacabaremos cultivando la vid en las cumbres de las monta\u00f1as?<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;Espero que no llegue a tanto, pero est\u00e1 claro que los vi\u00f1edos se ir\u00e1n desplazando a mayor altura (y tambi\u00e9n a otras latitudes) para compensar el aumento de temperaturas. Por cada 100 metros de altura, desciende casi un grado la temperatura y esto favorece la maduraci\u00f3n pausada de las uvas. Una de las consecuencias del calentamiento global, es que las vendimias se avanzan y esto puede provocar un desequilibrio en la maduraci\u00f3n de los diferentes componentes de la uva. Nosotros ya tenemos vi\u00f1edos en Tremp, en el prepirineo, a 950 metros de altura, y la calidad es muy buena, y otras fincas a 1.100 metros en las que todav\u00eda no estamos plantando porque hace demasiado fr\u00edo, pero no creo que tardemos en hacerlo. Sin embargo, estas vi\u00f1as en altura tienen una dificultad a\u00f1adida, ya que est\u00e1n m\u00e1s expuestas al granizo y esto nos obliga a instalar redes antigranizo para proteger la vendimia, lo que encarece la gesti\u00f3n del vi\u00f1edo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;<em>\u00bfEs posible que el cambio clim\u00e1tico acabe provocando que los sabores con los que identificamos ahora las principales DO de nuestro pa\u00eds cambien para siempre? <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;Los vinos ser\u00e1n diferentes porque cambiar\u00e1n las variedades que podamos cultivar en determinadas zonas. En algunas zonas, podr\u00edamos introducir monastrell en vez de tempranillo, y tempranillo en vez de pinot noir. Pero ya no ser\u00e1n los vinos a los que los consumidores est\u00e1n acostumbrados. Las DO deber\u00e1n adaptarse y autorizar nuevas variedades. Tambi\u00e9n cambiar\u00e1 el mapa de las DO porque surgir\u00e1n nuevas zonas para el cultivo de la vid y algunas de las actuales podr\u00edan desaparecer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;<em>\u00bfQu\u00e9 tiene que cambiar en los sectores productivos y en la sociedad en su conjunto para conseguir reducir las emisiones de carbono y no sobrepasar esos 1,5 grados de calentamiento global y evitar as\u00ed los peores escenarios? <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;Ya es pr\u00e1cticamente seguro a estas alturas que el Acuerdo de Par\u00eds, de limitar el aumento de las temperaturas a 1,5 o m\u00e1ximo dos grados a finales del siglo XXI, ser\u00e1 imposible. Seguimos teniendo una enorme dependencia de los combustibles f\u00f3siles, y el 81% del total de la demanda energ\u00e9tica de energ\u00eda primaria mundial corresponde al petr\u00f3leo, al carb\u00f3n, y al gas. En el caso del petr\u00f3leo, el consumo supera los 100 millones de barriles al d\u00eda. Y adem\u00e1s, las empresas del petr\u00f3leo reciben subsidios a escala mundial, del orden de 400.000 millones de d\u00f3lares, con el fin de evitar el incremento de la inflaci\u00f3n. As\u00ed que lo primordial es dejar de depender de los combustibles f\u00f3siles y utilizar energ\u00edas renovables. Tambi\u00e9n ayudar\u00eda si disminuimos el consumo de carne de nuestra dieta y reducimos el uso de pl\u00e1sticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;<em>La revista Science public\u00f3 en 2019 un informe que destacaba la reforestaci\u00f3n como una de las estrategias m\u00e1s efectivas para la mitigaci\u00f3n del cambio clim\u00e1tico. Una acci\u00f3n que promueven desde la IWCA.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;La plantaci\u00f3n de \u00e1rboles es, hoy por hoy, lo m\u00e1s eficaz que se puede hacer para conseguir disminuir esta capa de gases de efecto invernadero (GEI) que tenemos en la atm\u00f3sfera, y que proceden sobre todo de la combusti\u00f3n de la gasolina, el carb\u00f3n y el gas. Habr\u00eda que plantar 500.000 millones de \u00e1rboles para conseguir bajar un 25% estos GEI, que ascend\u00edan a finales del a\u00f1o pasado a 421 ppm [partes por mill\u00f3n] contra 270 ppm a finales del siglo XIX. Muchos pa\u00edses est\u00e1n haciendo esfuerzos en este sentido, muchas empresas tambi\u00e9n. En nuestro caso, queremos plantar dos millones de \u00e1rboles en los pr\u00f3ximos a\u00f1os, especialmente en Chile, donde disponemos de extensas fincas y tambi\u00e9n en Espa\u00f1a.<br>(elconfidencial.com)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como presidente y cofundador de las International Wineries for Climate Action (IWCA), y tras crear el programa Torres &amp; Earth para contribuir a mitigar el calentamiento global y promover la adaptaci\u00f3n al nuevo escenario clim\u00e1tico, Miguel A. Torres, centra ahora su labor en concienciar al sector vitivin\u00edcola y a la sociedad en su conjunto de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":10595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[75,76,77,29,26],"class_list":["post-10594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-caimaticombio-cl","tag-familia-torres","tag-miguel-torres","tag-vinas","tag-vinos"],"_links":{"self":[{"href":"https:\/\/www.todovinos.cl\/wp2\/wp-json\/wp\/v2\/posts\/10594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todovinos.cl\/wp2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todovinos.cl\/wp2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todovinos.cl\/wp2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todovinos.cl\/wp2\/wp-json\/wp\/v2\/comments?post=10594"}],"version-history":[{"count":3,"href":"https:\/\/www.todovinos.cl\/wp2\/wp-json\/wp\/v2\/posts\/10594\/revisions"}],"predecessor-version":[{"id":10598,"href":"https:\/\/www.todovinos.cl\/wp2\/wp-json\/wp\/v2\/posts\/10594\/revisions\/10598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todovinos.cl\/wp2\/wp-json\/wp\/v2\/media\/10595"}],"wp:attachment":[{"href":"https:\/\/www.todovinos.cl\/wp2\/wp-json\/wp\/v2\/media?parent=10594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todovinos.cl\/wp2\/wp-json\/wp\/v2\/categories?post=10594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todovinos.cl\/wp2\/wp-json\/wp\/v2\/tags?post=10594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}